{"id":778,"date":"2017-03-14T20:38:09","date_gmt":"2017-03-14T19:38:09","guid":{"rendered":"http:\/\/www.vendee1.eu\/vendee\/?p=778"},"modified":"2017-03-14T20:38:09","modified_gmt":"2017-03-14T19:38:09","slug":"coeurs-de-chouans","status":"publish","type":"post","link":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/","title":{"rendered":"Les coeurs de chouans"},"content":{"rendered":"<div id=\"vende-1161118280\" class=\"vende-ads-avant-contenu vende-entity-placement\"><div id=\"attachment_3409\" style=\"width: 810px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mediawakeup.fr\/nous-contacter-184-rue-joseph-gaillard-zone-dactivites-nord-et-gare-85600-montaigu-vendee-agence-crea-web-print\/\" target=\"_blank\" rel=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3409\" class=\"wp-image-3409 size-full\" title=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet\" src=\"https:\/\/www.vendee1.eu\/wp-content\/uploads\/2018\/03\/creation-site-internet-vendee-graphistes.jpg\" alt=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet - Agence de communication web print en Vend\u00e9e \" width=\"800\" height=\"283\" \/><\/a><p id=\"caption-attachment-3409\" class=\"wp-caption-text\">Cr\u00e9ation logo Vend\u00e9e Montaigu site internet &#8211; Agence de communication web print en Vend\u00e9e<\/p><\/div>\n<p>&nbsp;<\/p>\n<\/div><h1><span style=\"color: #800000;\">Les coeurs de chouans en Vend\u00e9e<br \/>\n<\/span><\/h1>\n<p style=\"text-align: justify;\">C&rsquo;est en Juin 1998, en Bretagne, que s&rsquo;est form\u00e9 un groupe de passionn\u00e9s&#8230; Notre passion ? Les guerres de Vend\u00e9e et de la Chouannerie qui se sont d\u00e9roul\u00e9es pendant la p\u00e9riode R\u00e9volutionnaire. \u00a0\u00bb Une page m\u00e9connue de l&rsquo;Histoire de France \u00ab\u00a0.<\/p>\n<p style=\"text-align: justify;\">La Troupe des Coeurs de Chouans est une Troupe costum\u00e9e compos\u00e9e de combattants des guerres de l&rsquo;Ouest (Paysans Vend\u00e9ens et Chouans, G\u00e9n\u00e9raux et Officiers de la Grande Arm\u00e9e Catholique et Royale, Amazones etc &#8230;). La m\u00e9moire de nos anc\u00eatres Vend\u00e9ens et Chouans qui se sont lev\u00e9s voil\u00e0 plus de deux cent ans pour d\u00e9fendre l&rsquo;Autel et le Tr\u00f4ne. Perp\u00e9tuer le souvenir de l&rsquo;\u00e9pop\u00e9e Chouanne et Vend\u00e9enne par l&rsquo;impact visuel produit par la Troupe costum\u00e9e.<\/p>\n<p style=\"text-align: justify;\">&#8211; Comm\u00e9morations li\u00e9es \u00e0 l&rsquo;Histoire.<br \/>\n&#8211; Bivouacs au coin du feu.<br \/>\n&#8211; Promenades culturelles et historiques sur les traces de nos anc\u00eatres \u00e0 travers la Vend\u00e9e Militaire, la Bretagne de la Chouannerie, et les r\u00e9gions travers\u00e9es lors de la \u00ab\u00a0Vir\u00e9e de Galerne.\u00a0\u00bb<br \/>\n&#8211; Faire descendre l&rsquo;Histoire dans la rue \u00e0 la demande de toutes les municipalit\u00e9s, par le biais de la reconstitution historique.<br \/>\n&#8211; De ce fait, nous pouvons animer des manifestations en collaboration avec des groupes professionnels de la reconstitution historique .<\/p>\n<p><img decoding=\"async\" title=\"coeurs de chouans\" src=\"..\/images\/artistes-vendeens\/coeurdechouans\/lescoeursdechouans.jpg\" alt=\"coeurs de chouans\" border=\"0\" \/><\/p>\n<p>Nous autres compagnons de la Hulotte, d\u00e9sirons faire revivre cette \u00e9poque devant le public . La m\u00e9moire au service du Souvenir et de la Culture. En nous pr\u00e9venant Deux mois \u00e0 l&rsquo;avance,\u00a0 un groupe de Dix chouans pourra se rendre disponible le Dimanche de pr\u00e9f\u00e9rence.<\/p>\n<p><img decoding=\"async\" title=\"coeurs de chouans\" src=\"..\/images\/artistes-vendeens\/coeurdechouans\/prov22.jpg\" alt=\"coeurs de chouans\" border=\"0\" \/><\/p>\n<p>Afin de renforcer l&rsquo;impact visuel, il nous est possible d&rsquo;organiser des combats, maniements\u00a0 d&rsquo;armes, saynettes etc &#8230; et ce, avec des effectifs pouvant aller jusqu&rsquo;\u00e0 une vingtaine de participants.<\/p>\n<p><img decoding=\"async\" title=\"coeurs de chouans\" src=\"..\/images\/artistes-vendeens\/coeurdechouans\/chouanbataille.jpg\" alt=\"coeurs de chouans\" border=\"0\" \/><\/p>\n<p><span style=\"color: #ff6600;\"><strong>Vid\u00e9o des Coeurs de Chouans :<\/strong><\/span><\/p>\n<p>\n<strong><a href=\"http:\/\/www.dailymotion.com\/video\/x87dei_coeurs-de-chouans-testament-louis-x_news\">Coeurs de Chouans &#8211; Testament Louis XVI<\/a><\/strong><br \/>\n<em>envoy\u00e9 par <a href=\"http:\/\/www.dailymotion.com\/SACR_videos\">SACR_videos<\/a>. &#8211; <a href=\"http:\/\/www.dailymotion.com\/fr\/channel\/news\" target=\"_self\">L&rsquo;actualit\u00e9 du moment en vid\u00e9o.<\/a><\/em><\/p>\n<p>Visitez le site des coeurs de chouans: http:\/\/lescoeursdechouans.free.fr<\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_052d84a954d66' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-778\">Avis visiteurs :<\/div><div id='yasr-vv-second-row-container-052d84a954d66'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-052d84a954d66'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='778'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='16'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='58f372a3f7'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-052d84a954d66\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"778\"\r\n                                   id=\"yasr-stats-dashicon-052d84a954d66\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-052d84a954d66\" class=\"yasr-vv-text-container\">[Nbre : <span id=\"yasr-vv-votes-number-container-052d84a954d66\">0<\/span>  Moyenne : <span id=\"yasr-vv-average-container-052d84a954d66\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-052d84a954d66' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-052d84a954d66' class='yasr-vv-bottom-container'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div><div id=\"vende-112098475\" class=\"vende-ads-apres-contenu vende-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: 10px;\"><p><a href=\"https:\/\/hellostickers.fr\" rel=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2282 \" title=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\" src=\"https:\/\/www.vendee1.eu\/vendee\/wp-content\/uploads\/2017\/05\/stickers_autocollants_decoratifs_regionaux-e1552677291609.png\" alt=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\" width=\"654\" height=\"121\" \/><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les coeurs de chouans en Vend\u00e9e C&rsquo;est en Juin 1998, en Bretagne, que s&rsquo;est form\u00e9 un groupe de passionn\u00e9s&#8230; Notre passion ? Les guerres de Vend\u00e9e et de la Chouannerie qui se sont d\u00e9roul\u00e9es&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-778","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les coeurs de chouans - Sorties en Vend\u00e9e, Tourisme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les coeurs de chouans - Sorties en Vend\u00e9e, Tourisme\" \/>\n<meta property=\"og:description\" content=\"Les coeurs de chouans en Vend\u00e9e C&rsquo;est en Juin 1998, en Bretagne, que s&rsquo;est form\u00e9 un groupe de passionn\u00e9s&#8230; Notre passion ? Les guerres de Vend\u00e9e et de la Chouannerie qui se sont d\u00e9roul\u00e9es&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/\" \/>\n<meta property=\"og:site_name\" content=\"Sorties en Vend\u00e9e, Tourisme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vendee.tourisme.7\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-14T19:38:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/..\/images\/artistes-vendeens\/coeurdechouans\/lescoeursdechouans.jpg\" \/>\n<meta name=\"author\" content=\"Sorties Vend\u00e9e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sorties Vend\u00e9e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/coeurs-de-chouans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/coeurs-de-chouans\\\/\"},\"author\":{\"name\":\"Sorties Vend\u00e9e\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\"},\"headline\":\"Les coeurs de chouans\",\"datePublished\":\"2017-03-14T19:38:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/coeurs-de-chouans\\\/\"},\"wordCount\":356,\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/coeurs-de-chouans\\\/\",\"url\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/coeurs-de-chouans\\\/\",\"name\":\"Les coeurs de chouans - Sorties en Vend\u00e9e, Tourisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#website\"},\"datePublished\":\"2017-03-14T19:38:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/coeurs-de-chouans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/coeurs-de-chouans\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/coeurs-de-chouans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les coeurs de chouans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#website\",\"url\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/\",\"name\":\"Sorties en Vend\u00e9e, Tourisme\",\"description\":\"Vend\u00e9e1, les id\u00e9es Sorties en Vend\u00e9e Tourisme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\",\"name\":\"Sorties Vend\u00e9e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"caption\":\"Sorties Vend\u00e9e\"}},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les coeurs de chouans - Sorties en Vend\u00e9e, Tourisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/","og_locale":"fr_FR","og_type":"article","og_title":"Les coeurs de chouans - Sorties en Vend\u00e9e, Tourisme","og_description":"Les coeurs de chouans en Vend\u00e9e C&rsquo;est en Juin 1998, en Bretagne, que s&rsquo;est form\u00e9 un groupe de passionn\u00e9s&#8230; Notre passion ? Les guerres de Vend\u00e9e et de la Chouannerie qui se sont d\u00e9roul\u00e9es&#46;&#46;&#46;","og_url":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/","og_site_name":"Sorties en Vend\u00e9e, Tourisme","article_publisher":"https:\/\/www.facebook.com\/vendee.tourisme.7\/","article_published_time":"2017-03-14T19:38:09+00:00","og_image":[{"url":"..\/images\/artistes-vendeens\/coeurdechouans\/lescoeursdechouans.jpg","type":"","width":"","height":""}],"author":"Sorties Vend\u00e9e","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sorties Vend\u00e9e","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/#article","isPartOf":{"@id":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/"},"author":{"name":"Sorties Vend\u00e9e","@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc"},"headline":"Les coeurs de chouans","datePublished":"2017-03-14T19:38:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/"},"wordCount":356,"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/","url":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/","name":"Les coeurs de chouans - Sorties en Vend\u00e9e, Tourisme","isPartOf":{"@id":"https:\/\/www.vendee1.eu\/vendee\/#website"},"datePublished":"2017-03-14T19:38:09+00:00","author":{"@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc"},"breadcrumb":{"@id":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vendee1.eu\/vendee\/coeurs-de-chouans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vendee1.eu\/vendee\/"},{"@type":"ListItem","position":2,"name":"Les coeurs de chouans"}]},{"@type":"WebSite","@id":"https:\/\/www.vendee1.eu\/vendee\/#website","url":"https:\/\/www.vendee1.eu\/vendee\/","name":"Sorties en Vend\u00e9e, Tourisme","description":"Vend\u00e9e1, les id\u00e9es Sorties en Vend\u00e9e Tourisme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vendee1.eu\/vendee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc","name":"Sorties Vend\u00e9e","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","caption":"Sorties Vend\u00e9e"}},false]}},"_links":{"self":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/comments?post=778"}],"version-history":[{"count":1,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/778\/revisions"}],"predecessor-version":[{"id":779,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/778\/revisions\/779"}],"wp:attachment":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/categories?post=778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/tags?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}