{"id":576,"date":"2017-03-14T07:45:02","date_gmt":"2017-03-14T06:45:02","guid":{"rendered":"http:\/\/www.vendee1.eu\/vendee\/?p=576"},"modified":"2017-03-14T07:45:02","modified_gmt":"2017-03-14T06:45:02","slug":"guide-de-vendee-accessible","status":"publish","type":"post","link":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/","title":{"rendered":"Guide de la Vend\u00e9e accessible"},"content":{"rendered":"<div id=\"vende-3358521883\" class=\"vende-ads-avant-contenu vende-entity-placement\"><div id=\"attachment_3409\" style=\"width: 810px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mediawakeup.fr\/nous-contacter-184-rue-joseph-gaillard-zone-dactivites-nord-et-gare-85600-montaigu-vendee-agence-crea-web-print\/\" target=\"_blank\" rel=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3409\" class=\"wp-image-3409 size-full\" title=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet\" src=\"https:\/\/www.vendee1.eu\/wp-content\/uploads\/2018\/03\/creation-site-internet-vendee-graphistes.jpg\" alt=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet - Agence de communication web print en Vend\u00e9e \" width=\"800\" height=\"283\" \/><\/a><p id=\"caption-attachment-3409\" class=\"wp-caption-text\">Cr\u00e9ation logo Vend\u00e9e Montaigu site internet &#8211; Agence de communication web print en Vend\u00e9e<\/p><\/div>\n<p>&nbsp;<\/p>\n<\/div><p style=\"text-align: justify;\">\u00a0<\/p>\n<h3><img decoding=\"async\" style=\"margin: 35px 5px; float: right; border: 0pt none;\" title=\"guide vend\u00e9e\" src=\"..\/images\/actualite\/guide-vendee-accessible.jpg\" alt=\"guide vend\u00e9e\" border=\"0\" \/>Un Guide pour une Vend\u00e9e<br \/>\nplus accessible.<\/h3>\n<p style=\"text-align: justify;\">\nLa d\u00e9couverte de la Vend\u00e9e, le patrimoine vend\u00e9en, sont aujourd&rsquo;hui rendus plus accessibles gr\u00e2ce \u00e0 un livre r\u00e9alis\u00e9 par Franck Vermet, lui-m\u00eame en fauteuil, \u00ab\u00a0Le Guide de la Vend\u00e9e accessible\u00a0\u00bb. Il permet aux personnes handicap\u00e9es d&rsquo;anticiper leurs excursions, leurs vacances et fournit des informations pratiques d&rsquo;accessibilit\u00e9 \u00e0 ces lieux touristiques (sch\u00e9mas, illustrations). Pour pouvoir r\u00e9aliser ce guide, il a fallu \u00e0 Franck Vernet visiter tous les sites, proc\u00e9der \u00e0 des mesures, r\u00e9pertorier les obstacles pour le passage d&rsquo;un fauteuil et fournir les solutions d&rsquo;accessibilit\u00e9. Ce guide est plut\u00f4t complet, il y mentionne \u00e9galement les \u00e9l\u00e9ments comme lavabos, toilettes, les marches et bien pens\u00e9, il a en effet \u00e9t\u00e9 r\u00e9alis\u00e9 avec une reliure spirale en vue d&rsquo;\u00eatre maintenu sur les genoux de la personnes handicap\u00e9es pendant sa visite. <\/p>\n<p>Le Comit\u00e9 D\u00e9partemental du Tourisme de la Vend\u00e9e a donc soutenu ce projet et permis de r\u00e9aliser ce guide. Si vous souhaitez vous procurer cet ouvrage, il est aujourd&rsquo;hui propos\u00e9 en librairie et par les guides Michelin &#8211; Collection Int\u00e9grance &#8211; Un livre de 312 pages en couleurs.<\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_e6a7a071d4b09' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-576\">Avis visiteurs :<\/div><div id='yasr-vv-second-row-container-e6a7a071d4b09'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-e6a7a071d4b09'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='576'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='16'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='58f372a3f7'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-e6a7a071d4b09\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"576\"\r\n                                   id=\"yasr-stats-dashicon-e6a7a071d4b09\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-e6a7a071d4b09\" class=\"yasr-vv-text-container\">[Nbre : <span id=\"yasr-vv-votes-number-container-e6a7a071d4b09\">0<\/span>  Moyenne : <span id=\"yasr-vv-average-container-e6a7a071d4b09\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-e6a7a071d4b09' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-e6a7a071d4b09' class='yasr-vv-bottom-container'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div><div id=\"vende-115593477\" class=\"vende-ads-apres-contenu vende-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: 10px;\"><p><a href=\"https:\/\/hellostickers.fr\" rel=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2282 \" title=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\" src=\"https:\/\/www.vendee1.eu\/vendee\/wp-content\/uploads\/2017\/05\/stickers_autocollants_decoratifs_regionaux-e1552677291609.png\" alt=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\" width=\"654\" height=\"121\" \/><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Un Guide pour une Vend\u00e9e plus accessible. La d\u00e9couverte de la Vend\u00e9e, le patrimoine vend\u00e9en, sont aujourd&rsquo;hui rendus plus accessibles gr\u00e2ce \u00e0 un livre r\u00e9alis\u00e9 par Franck Vermet, lui-m\u00eame en fauteuil, \u00ab\u00a0Le Guide&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-576","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guide de la Vend\u00e9e accessible - Sorties en Vend\u00e9e, Tourisme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guide de la Vend\u00e9e accessible - Sorties en Vend\u00e9e, Tourisme\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Un Guide pour une Vend\u00e9e plus accessible. La d\u00e9couverte de la Vend\u00e9e, le patrimoine vend\u00e9en, sont aujourd&rsquo;hui rendus plus accessibles gr\u00e2ce \u00e0 un livre r\u00e9alis\u00e9 par Franck Vermet, lui-m\u00eame en fauteuil, \u00ab\u00a0Le Guide&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/\" \/>\n<meta property=\"og:site_name\" content=\"Sorties en Vend\u00e9e, Tourisme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vendee.tourisme.7\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-14T06:45:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/..\/images\/actualite\/guide-vendee-accessible.jpg\" \/>\n<meta name=\"author\" content=\"Sorties Vend\u00e9e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sorties Vend\u00e9e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/guide-de-vendee-accessible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/guide-de-vendee-accessible\\\/\"},\"author\":{\"name\":\"Sorties Vend\u00e9e\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\"},\"headline\":\"Guide de la Vend\u00e9e accessible\",\"datePublished\":\"2017-03-14T06:45:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/guide-de-vendee-accessible\\\/\"},\"wordCount\":211,\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/guide-de-vendee-accessible\\\/\",\"url\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/guide-de-vendee-accessible\\\/\",\"name\":\"Guide de la Vend\u00e9e accessible - Sorties en Vend\u00e9e, Tourisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#website\"},\"datePublished\":\"2017-03-14T06:45:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/guide-de-vendee-accessible\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/guide-de-vendee-accessible\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/guide-de-vendee-accessible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guide de la Vend\u00e9e accessible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#website\",\"url\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/\",\"name\":\"Sorties en Vend\u00e9e, Tourisme\",\"description\":\"Vend\u00e9e1, les id\u00e9es Sorties en Vend\u00e9e Tourisme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\",\"name\":\"Sorties Vend\u00e9e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"caption\":\"Sorties Vend\u00e9e\"}},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guide de la Vend\u00e9e accessible - Sorties en Vend\u00e9e, Tourisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/","og_locale":"fr_FR","og_type":"article","og_title":"Guide de la Vend\u00e9e accessible - Sorties en Vend\u00e9e, Tourisme","og_description":"\u00a0 Un Guide pour une Vend\u00e9e plus accessible. La d\u00e9couverte de la Vend\u00e9e, le patrimoine vend\u00e9en, sont aujourd&rsquo;hui rendus plus accessibles gr\u00e2ce \u00e0 un livre r\u00e9alis\u00e9 par Franck Vermet, lui-m\u00eame en fauteuil, \u00ab\u00a0Le Guide&#46;&#46;&#46;","og_url":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/","og_site_name":"Sorties en Vend\u00e9e, Tourisme","article_publisher":"https:\/\/www.facebook.com\/vendee.tourisme.7\/","article_published_time":"2017-03-14T06:45:02+00:00","og_image":[{"url":"..\/images\/actualite\/guide-vendee-accessible.jpg","type":"","width":"","height":""}],"author":"Sorties Vend\u00e9e","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sorties Vend\u00e9e","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/#article","isPartOf":{"@id":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/"},"author":{"name":"Sorties Vend\u00e9e","@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc"},"headline":"Guide de la Vend\u00e9e accessible","datePublished":"2017-03-14T06:45:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/"},"wordCount":211,"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/","url":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/","name":"Guide de la Vend\u00e9e accessible - Sorties en Vend\u00e9e, Tourisme","isPartOf":{"@id":"https:\/\/www.vendee1.eu\/vendee\/#website"},"datePublished":"2017-03-14T06:45:02+00:00","author":{"@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc"},"breadcrumb":{"@id":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vendee1.eu\/vendee\/guide-de-vendee-accessible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vendee1.eu\/vendee\/"},{"@type":"ListItem","position":2,"name":"Guide de la Vend\u00e9e accessible"}]},{"@type":"WebSite","@id":"https:\/\/www.vendee1.eu\/vendee\/#website","url":"https:\/\/www.vendee1.eu\/vendee\/","name":"Sorties en Vend\u00e9e, Tourisme","description":"Vend\u00e9e1, les id\u00e9es Sorties en Vend\u00e9e Tourisme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vendee1.eu\/vendee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc","name":"Sorties Vend\u00e9e","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","caption":"Sorties Vend\u00e9e"}},false]}},"_links":{"self":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/comments?post=576"}],"version-history":[{"count":1,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/576\/revisions"}],"predecessor-version":[{"id":577,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/576\/revisions\/577"}],"wp:attachment":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/media?parent=576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/categories?post=576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/tags?post=576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}