{"id":1017,"date":"2017-03-17T08:12:10","date_gmt":"2017-03-17T07:12:10","guid":{"rendered":"http:\/\/www.vendee1.eu\/vendee\/?p=1017"},"modified":"2017-03-17T08:12:10","modified_gmt":"2017-03-17T07:12:10","slug":"bons-valets-de-challans","status":"publish","type":"post","link":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/","title":{"rendered":"Les bons valets de Challans"},"content":{"rendered":"<div id=\"vende-254796788\" class=\"vende-ads-avant-contenu vende-entity-placement\"><div id=\"attachment_3409\" style=\"width: 810px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mediawakeup.fr\/nous-contacter-184-rue-joseph-gaillard-zone-dactivites-nord-et-gare-85600-montaigu-vendee-agence-crea-web-print\/\" target=\"_blank\" rel=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3409\" class=\"wp-image-3409 size-full\" title=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet\" src=\"https:\/\/www.vendee1.eu\/wp-content\/uploads\/2018\/03\/creation-site-internet-vendee-graphistes.jpg\" alt=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet - Agence de communication web print en Vend\u00e9e \" width=\"800\" height=\"283\" \/><\/a><p id=\"caption-attachment-3409\" class=\"wp-caption-text\">Cr\u00e9ation logo Vend\u00e9e Montaigu site internet &#8211; Agence de communication web print en Vend\u00e9e<\/p><\/div>\n<p>&nbsp;<\/p>\n<\/div><h1>\n<span style=\"font-size: medium;\"><strong>Les bons valets de Challans <\/strong><\/span><br \/>\n<span style=\"font-size: x-small;\">(chansons anciennes de Vend\u00e9e)<\/span><\/h1>\n<p>&nbsp;<\/p>\n<p>Ce sont les valets de Challans (bis)<\/p>\n<p>Qui vont \u00e0 l&rsquo;ouvrage avec courage<\/p>\n<p>Ils vont doucement pour aller plus longtemps<\/p>\n<p>&nbsp;<\/p>\n<p>Ah c&rsquo;\u00e9tait lui qui b\u00fbchait notre bois (bis)<\/p>\n<p>Avec sa serpette ,il coupait les b\u00fbchettes<\/p>\n<p>Et les triquots\u00a0 les mettait en fagots<\/p>\n<p>&nbsp;<\/p>\n<p>Ah c&rsquo;\u00e9tait lui qui mangeait un morceau (bis )<\/p>\n<p>Un pain de 12 livres qu&rsquo;il mangeait \u00e0 la livre<\/p>\n<p>Encore disait-il\u00a0 je n&rsquo;ai pas d&rsquo;app\u00e9tit<\/p>\n<p>&nbsp;<\/p>\n<p>Ah c&rsquo;\u00e9tait lui qui buvait un bon coup (bis )<\/p>\n<p>Un bol de 10 litres qu&rsquo;il buvait \u00e0 la lire<\/p>\n<p>Encore disait-il\u00a0 il est b\u00e9 trop petit<\/p>\n<p>&nbsp;<\/p>\n<p>Ah c&rsquo;\u00e9tait lui qui virait b\u00e9 les cr\u00eapes<\/p>\n<p>Saute cr\u00eapette ,dans ma po\u00ealette<\/p>\n<p>Un demi-cent\u00a0 feront b\u00e9 mon content<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600;\">Refrain<\/span><\/p>\n<p>Tu s&rsquo;ras mon gendre\u00a0\u00a0 enfant ..bel enfant<\/p>\n<p>Tu s&rsquo;ras mon gendre\u00a0 ..bel enfant marachin\u00a0 (bis )<\/p>\n<p>Tu s&rsquo;ras mon gendre\u00a0 y a pas deux moyens<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_162624f0ca4b5' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-1017\">Avis visiteurs :<\/div><div id='yasr-vv-second-row-container-162624f0ca4b5'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-162624f0ca4b5'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='1017'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='16'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='00fc981fb8'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-162624f0ca4b5\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"1017\"\r\n                                   id=\"yasr-stats-dashicon-162624f0ca4b5\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-162624f0ca4b5\" class=\"yasr-vv-text-container\">[Nbre : <span id=\"yasr-vv-votes-number-container-162624f0ca4b5\">0<\/span>  Moyenne : <span id=\"yasr-vv-average-container-162624f0ca4b5\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-162624f0ca4b5' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-162624f0ca4b5' class='yasr-vv-bottom-container'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div><div id=\"vende-2138015418\" class=\"vende-ads-apres-contenu vende-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: 10px;\"><p><a href=\"https:\/\/hellostickers.fr\" rel=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2282 \" title=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\" src=\"https:\/\/www.vendee1.eu\/vendee\/wp-content\/uploads\/2017\/05\/stickers_autocollants_decoratifs_regionaux-e1552677291609.png\" alt=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\" width=\"654\" height=\"121\" \/><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Les bons valets de Challans (chansons anciennes de Vend\u00e9e) &nbsp; Ce sont les valets de Challans (bis) Qui vont \u00e0 l&rsquo;ouvrage avec courage Ils vont doucement pour aller plus longtemps &nbsp; Ah c&rsquo;\u00e9tait lui&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1017","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les bons valets de Challans - Sorties en Vend\u00e9e, Tourisme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les bons valets de Challans - Sorties en Vend\u00e9e, Tourisme\" \/>\n<meta property=\"og:description\" content=\"Les bons valets de Challans (chansons anciennes de Vend\u00e9e) &nbsp; Ce sont les valets de Challans (bis) Qui vont \u00e0 l&rsquo;ouvrage avec courage Ils vont doucement pour aller plus longtemps &nbsp; Ah c&rsquo;\u00e9tait lui&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/\" \/>\n<meta property=\"og:site_name\" content=\"Sorties en Vend\u00e9e, Tourisme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vendee.tourisme.7\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-17T07:12:10+00:00\" \/>\n<meta name=\"author\" content=\"Sorties Vend\u00e9e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sorties Vend\u00e9e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/bons-valets-de-challans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/bons-valets-de-challans\\\/\"},\"author\":{\"name\":\"Sorties Vend\u00e9e\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\"},\"headline\":\"Les bons valets de Challans\",\"datePublished\":\"2017-03-17T07:12:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/bons-valets-de-challans\\\/\"},\"wordCount\":172,\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/bons-valets-de-challans\\\/\",\"url\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/bons-valets-de-challans\\\/\",\"name\":\"Les bons valets de Challans - Sorties en Vend\u00e9e, Tourisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#website\"},\"datePublished\":\"2017-03-17T07:12:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/bons-valets-de-challans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/bons-valets-de-challans\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/bons-valets-de-challans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les bons valets de Challans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#website\",\"url\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/\",\"name\":\"Sorties en Vend\u00e9e, Tourisme\",\"description\":\"Vend\u00e9e1, les id\u00e9es Sorties en Vend\u00e9e Tourisme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\",\"name\":\"Sorties Vend\u00e9e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"caption\":\"Sorties Vend\u00e9e\"}},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les bons valets de Challans - Sorties en Vend\u00e9e, Tourisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/","og_locale":"fr_FR","og_type":"article","og_title":"Les bons valets de Challans - Sorties en Vend\u00e9e, Tourisme","og_description":"Les bons valets de Challans (chansons anciennes de Vend\u00e9e) &nbsp; Ce sont les valets de Challans (bis) Qui vont \u00e0 l&rsquo;ouvrage avec courage Ils vont doucement pour aller plus longtemps &nbsp; Ah c&rsquo;\u00e9tait lui&#46;&#46;&#46;","og_url":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/","og_site_name":"Sorties en Vend\u00e9e, Tourisme","article_publisher":"https:\/\/www.facebook.com\/vendee.tourisme.7\/","article_published_time":"2017-03-17T07:12:10+00:00","author":"Sorties Vend\u00e9e","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sorties Vend\u00e9e","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/#article","isPartOf":{"@id":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/"},"author":{"name":"Sorties Vend\u00e9e","@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc"},"headline":"Les bons valets de Challans","datePublished":"2017-03-17T07:12:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/"},"wordCount":172,"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/","url":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/","name":"Les bons valets de Challans - Sorties en Vend\u00e9e, Tourisme","isPartOf":{"@id":"https:\/\/www.vendee1.eu\/vendee\/#website"},"datePublished":"2017-03-17T07:12:10+00:00","author":{"@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc"},"breadcrumb":{"@id":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vendee1.eu\/vendee\/bons-valets-de-challans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vendee1.eu\/vendee\/"},{"@type":"ListItem","position":2,"name":"Les bons valets de Challans"}]},{"@type":"WebSite","@id":"https:\/\/www.vendee1.eu\/vendee\/#website","url":"https:\/\/www.vendee1.eu\/vendee\/","name":"Sorties en Vend\u00e9e, Tourisme","description":"Vend\u00e9e1, les id\u00e9es Sorties en Vend\u00e9e Tourisme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vendee1.eu\/vendee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc","name":"Sorties Vend\u00e9e","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","caption":"Sorties Vend\u00e9e"}},false]}},"_links":{"self":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/1017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/comments?post=1017"}],"version-history":[{"count":1,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/1017\/revisions"}],"predecessor-version":[{"id":1018,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/1017\/revisions\/1018"}],"wp:attachment":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/media?parent=1017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/categories?post=1017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/tags?post=1017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}