{"id":1002,"date":"2017-03-17T08:08:52","date_gmt":"2017-03-17T07:08:52","guid":{"rendered":"http:\/\/www.vendee1.eu\/vendee\/?p=1002"},"modified":"2017-03-17T08:08:52","modified_gmt":"2017-03-17T07:08:52","slug":"vendanges-en-vendee","status":"publish","type":"post","link":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/","title":{"rendered":"Vendanges en Vend\u00e9e"},"content":{"rendered":"<div id=\"vende-1203396903\" class=\"vende-ads-avant-contenu vende-entity-placement\"><div id=\"attachment_3409\" style=\"width: 810px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.mediawakeup.fr\/nous-contacter-184-rue-joseph-gaillard-zone-dactivites-nord-et-gare-85600-montaigu-vendee-agence-crea-web-print\/\" target=\"_blank\" rel=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3409\" class=\"wp-image-3409 size-full\" title=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet\" src=\"https:\/\/www.vendee1.eu\/wp-content\/uploads\/2018\/03\/creation-site-internet-vendee-graphistes.jpg\" alt=\"Cr\u00e9ation logo Vend\u00e9e Montaigu site internet - Agence de communication web print en Vend\u00e9e \" width=\"800\" height=\"283\" \/><\/a><p id=\"caption-attachment-3409\" class=\"wp-caption-text\">Cr\u00e9ation logo Vend\u00e9e Montaigu site internet &#8211; Agence de communication web print en Vend\u00e9e<\/p><\/div>\n<p>&nbsp;<\/p>\n<\/div><h1><span style=\"font-size: small; color: #ff6600;\">Vendanges en Vend\u00e9e<\/span><br \/>\n<span style=\"font-size: x-small;\"><strong>Chanson vend\u00e9enne<\/p>\n<p><\/strong><\/span><\/h1>\n<p>Elle est fille du bocage<\/p>\n<p>Elle habite un blanc village<\/p>\n<p>Qui s&rsquo;accroche \u00e0 nos coteaux<\/p>\n<p>Coquette mais jamais vaine<\/p>\n<p>Elle fait en Vendeenne<\/p>\n<p>Claquer ses mignons sabots<\/p>\n<p>&nbsp;<\/p>\n<p>Sa robe rouge trouss\u00e9e<\/p>\n<p>Elle avait l&rsquo;air d&rsquo;une f\u00e9e<\/p>\n<p>Elle me souriait toujours<\/p>\n<p>Quelle joyeuse vendange<\/p>\n<p>O\u00f9 se fit le doux \u00e9change<\/p>\n<p>De nos premiers mots d&rsquo;amour<\/p>\n<p>Sa voix dans le ciel aust\u00e8re<\/p>\n<p>Mettait une note claire<\/p>\n<p>Je l&rsquo;\u00e9coutais plein d&rsquo;\u00e9moi<\/p>\n<p>J&rsquo;\u00e9tais l&rsquo; plus heureux du monde<\/p>\n<p>Quand parmi les grappes blondes<\/p>\n<p>Mes doigts rencontraient ses doigts<\/p>\n<p>&nbsp;<\/p>\n<p>Refrain<\/p>\n<p>Que la soir\u00e9e \u00e9tait belle<\/p>\n<p>Dans le fief de st Mich\u00e2<\/p>\n<p>Je vendangeais avec elle<\/p>\n<p>Du Gaillard et ddu Noah<\/p>\n<p>&nbsp;<\/p>\n<p>Quand la journ\u00e9e s&rsquo;est \u00e9teinte<\/p>\n<p>A l&rsquo;heure o\u00f9 l&rsquo;ang\u00e9lus tinte<\/p>\n<p>Nous revenions tous les deux<\/p>\n<p>Nous \u00e9coutions en silence<\/p>\n<p>Nos coeurs battre en cadence<\/p>\n<p>Surpris de leurs doux aveux<\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><!--Yasr Visitor Votes Shortcode--><div id='yasr_visitor_votes_30464c09a3e5e' class='yasr-visitor-votes'><div class=\"yasr-custom-text-vv-before yasr-custom-text-vv-before-1002\">Avis visiteurs :<\/div><div id='yasr-vv-second-row-container-30464c09a3e5e'\r\n                                        class='yasr-vv-second-row-container'><div id='yasr-visitor-votes-rater-30464c09a3e5e'\r\n                                      class='yasr-rater-stars-vv'\r\n                                      data-rater-postid='1002'\r\n                                      data-rating='0'\r\n                                      data-rater-starsize='16'\r\n                                      data-rater-readonly='false'\r\n                                      data-rater-nonce='58f372a3f7'\r\n                                      data-issingular='false'\r\n                                    ><\/div><div class=\"yasr-vv-stats-text-container\" id=\"yasr-vv-stats-text-container-30464c09a3e5e\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\"\r\n                                   class=\"yasr-dashicons-visitor-stats\"\r\n                                   data-postid=\"1002\"\r\n                                   id=\"yasr-stats-dashicon-30464c09a3e5e\">\r\n                                   <path d=\"M18 18v-16h-4v16h4zM12 18v-11h-4v11h4zM6 18v-8h-4v8h4z\"><\/path>\r\n                               <\/svg><span id=\"yasr-vv-text-container-30464c09a3e5e\" class=\"yasr-vv-text-container\">[Nbre : <span id=\"yasr-vv-votes-number-container-30464c09a3e5e\">0<\/span>  Moyenne : <span id=\"yasr-vv-average-container-30464c09a3e5e\">0<\/span>]<\/span><\/div><div id='yasr-vv-loader-30464c09a3e5e' class='yasr-vv-container-loader'><\/div><\/div><div id='yasr-vv-bottom-container-30464c09a3e5e' class='yasr-vv-bottom-container'><\/div><\/div><!--End Yasr Visitor Votes Shortcode--><\/div><div id=\"vende-907086196\" class=\"vende-ads-apres-contenu vende-entity-placement\" style=\"margin-top: 10px;margin-bottom: 10px;margin-left: 10px;\"><p><a href=\"https:\/\/hellostickers.fr\" rel=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2282 \" title=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\" src=\"https:\/\/www.vendee1.eu\/vendee\/wp-content\/uploads\/2017\/05\/stickers_autocollants_decoratifs_regionaux-e1552677291609.png\" alt=\"stickers autocollants decoratifs personnalis\u00e9s regionaux\" width=\"654\" height=\"121\" \/><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Vendanges en Vend\u00e9e Chanson vend\u00e9enne Elle est fille du bocage Elle habite un blanc village Qui s&rsquo;accroche \u00e0 nos coteaux Coquette mais jamais vaine Elle fait en Vendeenne Claquer ses mignons sabots &nbsp; Sa&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1002","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vendanges en Vend\u00e9e - Sorties en Vend\u00e9e, Tourisme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vendanges en Vend\u00e9e - Sorties en Vend\u00e9e, Tourisme\" \/>\n<meta property=\"og:description\" content=\"Vendanges en Vend\u00e9e Chanson vend\u00e9enne Elle est fille du bocage Elle habite un blanc village Qui s&rsquo;accroche \u00e0 nos coteaux Coquette mais jamais vaine Elle fait en Vendeenne Claquer ses mignons sabots &nbsp; Sa&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/\" \/>\n<meta property=\"og:site_name\" content=\"Sorties en Vend\u00e9e, Tourisme\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vendee.tourisme.7\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-17T07:08:52+00:00\" \/>\n<meta name=\"author\" content=\"Sorties Vend\u00e9e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sorties Vend\u00e9e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/vendanges-en-vendee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/vendanges-en-vendee\\\/\"},\"author\":{\"name\":\"Sorties Vend\u00e9e\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\"},\"headline\":\"Vendanges en Vend\u00e9e\",\"datePublished\":\"2017-03-17T07:08:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/vendanges-en-vendee\\\/\"},\"wordCount\":163,\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/vendanges-en-vendee\\\/\",\"url\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/vendanges-en-vendee\\\/\",\"name\":\"Vendanges en Vend\u00e9e - Sorties en Vend\u00e9e, Tourisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#website\"},\"datePublished\":\"2017-03-17T07:08:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/vendanges-en-vendee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/vendanges-en-vendee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/vendanges-en-vendee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendanges en Vend\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#website\",\"url\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/\",\"name\":\"Sorties en Vend\u00e9e, Tourisme\",\"description\":\"Vend\u00e9e1, les id\u00e9es Sorties en Vend\u00e9e Tourisme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vendee1.eu\\\/vendee\\\/#\\\/schema\\\/person\\\/63e22c035c30bbdf6ae725e3b531afdc\",\"name\":\"Sorties Vend\u00e9e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g\",\"caption\":\"Sorties Vend\u00e9e\"}},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vendanges en Vend\u00e9e - Sorties en Vend\u00e9e, Tourisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/","og_locale":"fr_FR","og_type":"article","og_title":"Vendanges en Vend\u00e9e - Sorties en Vend\u00e9e, Tourisme","og_description":"Vendanges en Vend\u00e9e Chanson vend\u00e9enne Elle est fille du bocage Elle habite un blanc village Qui s&rsquo;accroche \u00e0 nos coteaux Coquette mais jamais vaine Elle fait en Vendeenne Claquer ses mignons sabots &nbsp; Sa&#46;&#46;&#46;","og_url":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/","og_site_name":"Sorties en Vend\u00e9e, Tourisme","article_publisher":"https:\/\/www.facebook.com\/vendee.tourisme.7\/","article_published_time":"2017-03-17T07:08:52+00:00","author":"Sorties Vend\u00e9e","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sorties Vend\u00e9e","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/#article","isPartOf":{"@id":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/"},"author":{"name":"Sorties Vend\u00e9e","@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc"},"headline":"Vendanges en Vend\u00e9e","datePublished":"2017-03-17T07:08:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/"},"wordCount":163,"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/","url":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/","name":"Vendanges en Vend\u00e9e - Sorties en Vend\u00e9e, Tourisme","isPartOf":{"@id":"https:\/\/www.vendee1.eu\/vendee\/#website"},"datePublished":"2017-03-17T07:08:52+00:00","author":{"@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc"},"breadcrumb":{"@id":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vendee1.eu\/vendee\/vendanges-en-vendee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vendee1.eu\/vendee\/"},{"@type":"ListItem","position":2,"name":"Vendanges en Vend\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.vendee1.eu\/vendee\/#website","url":"https:\/\/www.vendee1.eu\/vendee\/","name":"Sorties en Vend\u00e9e, Tourisme","description":"Vend\u00e9e1, les id\u00e9es Sorties en Vend\u00e9e Tourisme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vendee1.eu\/vendee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.vendee1.eu\/vendee\/#\/schema\/person\/63e22c035c30bbdf6ae725e3b531afdc","name":"Sorties Vend\u00e9e","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61d1de7f953f29bb3f5b6457b62fb4b66f834c865f75a7d8ec767d557a808e20?s=96&d=mm&r=g","caption":"Sorties Vend\u00e9e"}},false]}},"_links":{"self":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/1002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/comments?post=1002"}],"version-history":[{"count":2,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/1002\/revisions"}],"predecessor-version":[{"id":1004,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/posts\/1002\/revisions\/1004"}],"wp:attachment":[{"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/media?parent=1002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/categories?post=1002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vendee1.eu\/vendee\/wp-json\/wp\/v2\/tags?post=1002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}